{"id":104865,"date":"2022-10-10T17:32:05","date_gmt":"2022-10-10T15:32:05","guid":{"rendered":"https:\/\/alpine-world.com\/shop\/?post_type=product&#038;p=104865"},"modified":"2026-07-15T04:11:49","modified_gmt":"2026-07-15T02:11:49","slug":"mammut-taiss-guide-so-pants","status":"publish","type":"product","link":"https:\/\/alpine-world.com\/shop\/prodotto\/mammut-taiss-guide-so-pants\/","title":{"rendered":"Mammut Taiss Guide SO Pants"},"content":{"rendered":"<p>I pantaloni softshell Mammut Taiss Guide SO Pants offrono la migliore protezione dagli agenti atmosferici. Sviluppati per l'alpinismo e lo scialpinismo. Il robusto tessuto a membrana a 3 strati \u00e8 completamente antivento e, grazie alla sua impermeabilizzazione priva di PFC, offre una protezione affidabile anche nelle condizioni pi\u00f9 difficili. Zip di ventilazione, chiusure elastiche in velcro in vita e regolazioni in velcro sull'orlo garantiscono un comfort e una vestibilit\u00e0 perfetti. Il Mammut Taiss Guide SO Pants \u00e8 leggero e ha molte altre caratteristiche, come tasche con cerniera compatibili con l'imbracatura da arrampicata e orli rinforzati delle gambe per proteggere dallo sfregamento delle lamine degli sci e dei ramponi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I pantaloni softshell Mammut Taiss Guide SO Pants offrono la migliore protezione dagli agenti atmosferici. Sviluppati per l'alpinismo e lo scialpinismo. Il robusto tessuto a membrana a 3 strati \u00e8 completamente antivento e, grazie alla sua impermeabilizzazione priva di PFC, offre una protezione affidabile anche nelle condizioni pi\u00f9 difficili. Zip di ventilazione, chiusure elastiche in [&hellip;]<\/p>\n","protected":false},"featured_media":104991,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"Mammut Taiss Guide SO Pants - Pantaloni per scialpinismo","_seopress_titles_desc":"I pantaloni softshell Mammut Taiss Guide SO Pants offrono la migliore protezione dagli agenti atmosferici. Sviluppati per l'alpinismo e lo scialpinismo.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","ep_exclude_from_search":false},"product_brand":[],"product_cat":[925,1920,1056,2919,1930,1034,1055],"product_tag":[2969,2994,2995],"class_list":{"0":"post-104865","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-abbigliamento","7":"product_cat-abbigliamento-sportivo-uomo","8":"product_cat-alpinismo","9":"product_cat-cascate-di-ghiaccio","10":"product_cat-pantaloni-e-short-sportivi-uomo","11":"product_cat-saldi","12":"product_cat-scialpinismo","13":"product_tag-alpinismo","14":"product_tag-cascate-di-ghiaccio","15":"product_tag-scialpinismo","16":"pa_categoria-pantaloni","17":"pa_colore-blu-scuro","18":"pa_colore-nero","19":"pa_colore-viola","20":"pa_taglia-44-eu-it","21":"pa_taglia-46-eu-it","22":"pa_taglia-48-eu-it","23":"pa_taglia-50-eu-it","24":"pa_taglia-52-eu","25":"yith_product_brand-mammut","27":"first","28":"instock","29":"sale","30":"taxable","31":"shipping-taxable","32":"purchasable","33":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/alpine-world.com\/shop\/wp-json\/wp\/v2\/product\/104865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpine-world.com\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/alpine-world.com\/shop\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alpine-world.com\/shop\/wp-json\/wp\/v2\/media\/104991"}],"wp:attachment":[{"href":"https:\/\/alpine-world.com\/shop\/wp-json\/wp\/v2\/media?parent=104865"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/alpine-world.com\/shop\/wp-json\/wp\/v2\/product_brand?post=104865"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/alpine-world.com\/shop\/wp-json\/wp\/v2\/product_cat?post=104865"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/alpine-world.com\/shop\/wp-json\/wp\/v2\/product_tag?post=104865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}